{"id":33187,"date":"2016-09-01T12:47:36","date_gmt":"2016-09-01T10:47:36","guid":{"rendered":"https:\/\/www.ideiakbizirik.com\/2016\/09\/01\/hitzaldi-workshop-marcela-fernandez-coachekin\/"},"modified":"2016-09-01T12:47:36","modified_gmt":"2016-09-01T12:47:36","slug":"hitzaldi-workshop-marcela-fernandez-coachekin","status":"publish","type":"post","link":"https:\/\/www.ideiakbizirik.com\/eu\/2016\/09\/01\/hitzaldi-workshop-marcela-fernandez-coachekin\/","title":{"rendered":"Hitzaldi + workshop Marcela Fern\u00e1ndez coachekin"},"content":{"rendered":"<p>Hitzaldi interesgarri bat izango da bihar, ostirala, 18:00etan Donostiako Innogune eraikinean, Marcela Fern\u00e1ndez <em>coach<\/em>ekin.<\/p>\n<p><u>Marcela Fernandez:<\/u><\/p>\n<p>ON board-en fundatzailea. Ikaskuntzako bidaiak dira. Bidaiatuz ikasteko kontzeptuan oinarritzen da.<\/p>\n<p>Bidaiatzeko eta nomada izateko duen izaera dela eta deskubritu du mundua. 50 herrialde bisitatu ditu eta 6 hizkuntzez mintzatzen da.<\/p>\n<p>Hondamendi naturalen biktimei lagundu die, hala nola Filipinetako Yolanda tifoiak eragindakoei eta Kolonbiako gerrak eragindako tragediei aurre egin zien.<\/p>\n<p>Ohikoa ez den hezkuntza ere aukera bat dela frogatzea da bizitzan daukan helburua. Hezkuntza alternatiboari buruzko eduAction izeneko dokumentalarekin tresnak eta zubiak sortu nahi ditu ohikoa ez den bide bati jarraitu nahi diotenentzat.<\/p>\n<p>Nazioarteko speaker eta Flow consultant izan da 8 herrialdetan baino gehiagotan. 2000 kupoi baino gehiago eman dira Flow delakoa suspertzeko eta pertsonak une ahaztezinak bizitzera gonbidatzeko.<\/p>\n<p><img decoding=\"async\" class=\"alignnone size-medium wp-image-4349\" src=\"https:\/\/www.ideiakbizirik.com\/wp-content\/uploads\/2016\/09\/Marcela_Fernandez-iuPlan-200x300.jpg\" alt=\"Marcela_Fernandez-iuPlan\" width=\"200\" height=\"300\" srcset=\"https:\/\/www.ideiakbizirik.com\/wp-content\/uploads\/2016\/09\/Marcela_Fernandez-iuPlan-200x300.jpg 200w, https:\/\/www.ideiakbizirik.com\/wp-content\/uploads\/2016\/09\/Marcela_Fernandez-iuPlan.jpg 600w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hitzaldi interesgarri bat izango da bihar, ostirala, 18:00etan Donostiako Innogune eraikinean, Marcela Fern\u00e1ndez coachekin. Marcela Fernandez: ON board-en fundatzailea. Ikaskuntzako bidaiak dira. Bidaiatuz ikasteko kontzeptuan oinarritzen da. Bidaiatzeko eta nomada izateko duen izaera dela eta deskubritu du mundua. 50 herrialde bisitatu ditu eta 6 hizkuntzez mintzatzen da. Hondamendi naturalen biktimei lagundu die, hala nola Filipinetako&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_robots_follow":"","_seopress_robots_imageindex":"","_seopress_robots_snippet":"","_seopress_robots_primary_cat":"","_seopress_robots_breadcrumbs":"","_seopress_robots_freeze_modified_date":"","_seopress_robots_custom_modified_date":"","_seopress_robots_canonical":"","_seopress_social_fb_title":"","_seopress_social_fb_desc":"","_seopress_social_fb_img":"","_seopress_social_fb_img_attachment_id":0,"_seopress_social_fb_img_width":0,"_seopress_social_fb_img_height":0,"_seopress_social_twitter_title":"","_seopress_social_twitter_desc":"","_seopress_social_twitter_img":"","_seopress_social_twitter_img_attachment_id":0,"_seopress_social_twitter_img_width":0,"_seopress_social_twitter_img_height":0,"_seopress_redirections_value":"","_seopress_redirections_enabled":"","_seopress_redirections_enabled_regex":"","_seopress_redirections_logged_status":"","_seopress_redirections_param":"","_seopress_redirections_type":0,"_seopress_analysis_target_kw":"","footnotes":""},"categories":[4382],"tags":[],"class_list":["post-33187","post","type-post","status-publish","format-standard","hentry","category-sailkatu-gabea"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.ideiakbizirik.com\/eu\/wp-json\/wp\/v2\/posts\/33187","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ideiakbizirik.com\/eu\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ideiakbizirik.com\/eu\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ideiakbizirik.com\/eu\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ideiakbizirik.com\/eu\/wp-json\/wp\/v2\/comments?post=33187"}],"version-history":[{"count":0,"href":"https:\/\/www.ideiakbizirik.com\/eu\/wp-json\/wp\/v2\/posts\/33187\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.ideiakbizirik.com\/eu\/wp-json\/wp\/v2\/media?parent=33187"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ideiakbizirik.com\/eu\/wp-json\/wp\/v2\/categories?post=33187"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ideiakbizirik.com\/eu\/wp-json\/wp\/v2\/tags?post=33187"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}