{"id":37420,"date":"2023-03-17T08:49:01","date_gmt":"2023-03-17T07:49:01","guid":{"rendered":"https:\/\/www.ideiakbizirik.com\/2023\/03\/17\/gipuzkoan-plastikoaren-ekonomia-zirkularreko-berrikuntza-poloa-garatzeko-dirulaguntza\/"},"modified":"2023-03-17T08:49:01","modified_gmt":"2023-03-17T07:49:01","slug":"gipuzkoan-plastikoaren-ekonomia-zirkularreko-berrikuntza-poloa-garatzeko-dirulaguntza","status":"publish","type":"post","link":"https:\/\/www.ideiakbizirik.com\/eu\/2023\/03\/17\/gipuzkoan-plastikoaren-ekonomia-zirkularreko-berrikuntza-poloa-garatzeko-dirulaguntza\/","title":{"rendered":"Gipuzkoan plastikoaren ekonomia zirkularreko berrikuntza-poloa garatzeko dirulaguntza."},"content":{"rendered":"<p>Dirulaguntza honen oinarri arautzaileak eta 2023ko deialdia onestea: Gipuzkoan plastikoaren ekonomia zirkularreko berrikuntza-poloa garatzeko dirulaguntza.<\/p>\n<p>Dirulaguntza lerro honen helburua da Gipuzkoan plastikoa birziklatzeko erreferentziazko berrikuntza polo bat sustatzea eta eraikitzea, zeina, batez ere, birziklatutako materiala lortzean zentratuta egongo den, ondoren plastiko birjin berriak fabrikatzeko bigarren mailako lehengai gisa erabiltzeko. Ezarriko den instalazioa materiala balorizatzeko instalazio bat izango da, eta alde batera utziko da Europako hondakinen hierarkiaren arabera hierarkia-maila apalagoa duen prozesu bat planteatzen duen edozein teknologia. <strong>EPEA: <\/strong>20 egun baliodun\u00a0 \u2022\u00a0 <a href=\"https:\/\/egoitza.gipuzkoa.eus\/gao-bog\/euskera\/gao\/2023\/03\/17\/e2301945.htm\"><strong>GAO<\/strong><\/a><\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dirulaguntza honen oinarri arautzaileak eta 2023ko deialdia onestea: Gipuzkoan plastikoaren ekonomia zirkularreko berrikuntza-poloa garatzeko dirulaguntza. Dirulaguntza lerro honen helburua da Gipuzkoan plastikoa birziklatzeko erreferentziazko berrikuntza polo bat sustatzea eta eraikitzea, zeina, batez ere, birziklatutako materiala lortzean zentratuta egongo den, ondoren plastiko birjin berriak fabrikatzeko bigarren mailako lehengai gisa erabiltzeko. Ezarriko den instalazioa materiala balorizatzeko instalazio&#8230;<\/p>\n","protected":false},"author":3,"featured_media":40390,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_robots_follow":"","_seopress_robots_imageindex":"","_seopress_robots_snippet":"","_seopress_robots_primary_cat":"","_seopress_robots_breadcrumbs":"","_seopress_robots_freeze_modified_date":"","_seopress_robots_custom_modified_date":"","_seopress_robots_canonical":"","_seopress_social_fb_title":"","_seopress_social_fb_desc":"","_seopress_social_fb_img":"","_seopress_social_fb_img_attachment_id":0,"_seopress_social_fb_img_width":0,"_seopress_social_fb_img_height":0,"_seopress_social_twitter_title":"","_seopress_social_twitter_desc":"","_seopress_social_twitter_img":"","_seopress_social_twitter_img_attachment_id":0,"_seopress_social_twitter_img_width":0,"_seopress_social_twitter_img_height":0,"_seopress_redirections_value":"","_seopress_redirections_enabled":"","_seopress_redirections_enabled_regex":"","_seopress_redirections_logged_status":"","_seopress_redirections_param":"","_seopress_redirections_type":0,"_seopress_analysis_target_kw":"","footnotes":""},"categories":[4371,4346,4341],"tags":[],"class_list":["post-37420","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-berrikuntza","category-ekintzaile-komunitatea","category-laguntzak"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.ideiakbizirik.com\/eu\/wp-json\/wp\/v2\/posts\/37420","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ideiakbizirik.com\/eu\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ideiakbizirik.com\/eu\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ideiakbizirik.com\/eu\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ideiakbizirik.com\/eu\/wp-json\/wp\/v2\/comments?post=37420"}],"version-history":[{"count":0,"href":"https:\/\/www.ideiakbizirik.com\/eu\/wp-json\/wp\/v2\/posts\/37420\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ideiakbizirik.com\/eu\/wp-json\/wp\/v2\/media\/40390"}],"wp:attachment":[{"href":"https:\/\/www.ideiakbizirik.com\/eu\/wp-json\/wp\/v2\/media?parent=37420"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ideiakbizirik.com\/eu\/wp-json\/wp\/v2\/categories?post=37420"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ideiakbizirik.com\/eu\/wp-json\/wp\/v2\/tags?post=37420"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}