{"id":37850,"date":"2023-10-04T07:30:49","date_gmt":"2023-10-04T05:30:49","guid":{"rendered":"https:\/\/www.ideiakbizirik.com\/2023\/10\/04\/elektronika-informazio-eta-komunikazio-teknologiei-buruzko-aholkularitza-teknologikoko-saioak-eikt-91\/"},"modified":"2023-10-04T07:30:49","modified_gmt":"2023-10-04T05:30:49","slug":"elektronika-informazio-eta-komunikazio-teknologiei-buruzko-aholkularitza-teknologikoko-saioak-eikt-91","status":"publish","type":"post","link":"https:\/\/www.ideiakbizirik.com\/eu\/2023\/10\/04\/elektronika-informazio-eta-komunikazio-teknologiei-buruzko-aholkularitza-teknologikoko-saioak-eikt-91\/","title":{"rendered":"Elektronika, Informazio eta Komunikazio Teknologiei buruzko aholkularitza teknologikoko saioak (EIKT)"},"content":{"rendered":"<p><strong>Bidasoa bizirik<\/strong>-ek, <strong>SPRI<\/strong>rekin lankidetzan, <a href=\"https:\/\/www.spri.eus\/laguntzak\/mikroenpresa-digitala\/\">aholkularitza teknologikoko saioak antolatzen ditu Elektronika, Informazio eta Komunikazio Teknologietan (EIKT),<\/a> pertsona autonomoei, ekintzaileei eta mikroenpresei beren negozioak teknologien bidez berrabiarazten laguntzeko eta aldaketetara egokitzeko, bezero konektatuagoekin eta zerbitzu berrietarako aukerekin. Aholkularitza teknologiko pertsonalizatua da, parte hartzen duten pertsonen eta mikroenpresen behar berezietara egokitua.<\/p>\n<p><strong>Eraldaketa Digita<\/strong>leko ibilbide horretan, parte hartzen duten pertsona ekintzaile eta mikroenpresek gutxienez hiru lantegitan eman beharko dute izena, eta horien ondoren banakako aholkularitza eskatu ahal izango dute eskuratutako gaitasunak sakondu edo finkatzeko.<\/p>\n<p>Saioak gure bulegoetan egiten dira (Ducoureau Jauregia, Hendaia kalea, 8-IRUN), 10:00etatik 13:00etara, gai hauekin:<\/p>\n<ul>\n<li><a style=\"color: #008080;\" href=\"https:\/\/www.ideiakbizirik.com\/wp-content\/uploads\/2023\/01\/1-INPL2023_Folleto-Gestion-Digital-feb.pdf\"><em><strong>Egin jauzi kudeaketa digitalera &#8211; Aurreztu denbora eta izan azkarrago teknologia errazenekin<\/strong><\/em> <\/a>(<strong>otsailaren 16an)<\/strong>\u00a0<\/li>\n<li><a style=\"color: #008080; text-decoration: underline;\" href=\"https:\/\/www.bidasoa-activa.com\/eu\/cursos-y-talleres\/inp02023inplantalariak-antolatu-paperik-gabeko-zure-bulegoa-emankorragoa-eta-iraunkorragoa-izateko-paperik-gabeko-bulegoa-martxoak-9a\/\"><strong>Antolatu paperik gabeko zure bulegoa emankorragoa eta iraunkorragoa izateko \u2013 Paperik Gabeko Bulegoa<\/strong><\/a> ( <strong>martxoak 9a) <\/strong><\/li>\n<li><a style=\"color: #008000;\" href=\"https:\/\/www.ideiakbizirik.com\/wp-content\/uploads\/2023\/01\/5-INPL2023_Folleto-IA-para-Web-jun.pdf\"><strong>Zabaldu zure negozioa mapetan eta bitarteko birtualetan, bezeroek lehiakideei baino lehenago aurki zaitzaten<\/strong><\/a> (<strong>maiatzaren 4a)\u00a0<\/strong><\/li>\n<li><a style=\"color: #008080;\" href=\"https:\/\/www.bidasoa-activa.com\/eu\/cursos-y-talleres\/inp03-023inplantalariak-zabaldu-zure-negozioa-mapetan-eta-bitarteko-birtualetan-bezeroek-lehiakideei-baino-lehenago-aurki-zaitzaten-maiatzaren-4a\/\"><strong>Produktuak eta zerbitzuak sustatu eta saldu zure bezeroa dagoen kanaletan\u00a0 &#8211; Zure katalogo digital irisgarria<\/strong><\/a> (<strong>maiatzaren 25a)\u00a0<\/strong><\/li>\n<li><a style=\"color: #008080;\" href=\"https:\/\/www.bidasoa-activa.com\/es\/cursos-y-talleres\/inp05023-inplantalariak-amplia-y-mejora-la-interaccion-y-atencion-al-cliente-a-traves-de-la-inteligencia-artificial-8-de-junio\/\"><strong>Zabaldu eta Hobetu Bezeroarekiko interakzioa eta haiekiko Arreta Adimen Artifizialaren bidez<\/strong><\/a>\u00a0(<strong>ekainaren 8a)\u00a0<\/strong><\/li>\n<li><a href=\"https:\/\/www.ideiakbizirik.com\/wp-content\/uploads\/2023\/01\/6-INPL2023_Folleto-Dispositivos-moviles-sep.pdf\"><strong>Zure negozioa gailu batean \u2013 Bihurtu mugikorra zure bulegoan<\/strong> <\/a>(<strong>irailaren 28a)\u00a0<\/strong><\/li>\n<li><strong><a href=\"https:\/\/www.ideiakbizirik.com\/wp-content\/uploads\/2023\/09\/7-INPL2023_Folleto-Ciberseguridad-oct.pdf\"><strong>Zibersegurtasuna lapurtua ez izateko<\/strong><\/a>\u00a0(<\/strong><strong>urriaren 19a)\u00a0 <a href=\"https:\/\/www.bidasoa-activa.com\/eu\/cursos-y-talleres\/inp07023inplantalariak-zibersegurtasuna-lapurtua-ez-izateko-azaroaren-16a\/\">IZEN-EMATE IREKIA<\/a><\/strong><\/li>\n<li><strong>\u00a0<a style=\"color: #008080;\" href=\"https:\/\/www.ideiakbizirik.com\/wp-content\/uploads\/2023\/09\/8-INPL2023_Folleto-RVNFTMetaverso-nov.pdf\">Ezagutu nola Errealitate Birtualak, Metaversoak eta NFTek zure negozioa handitu dezaketen<\/a>(<\/strong><strong>azaroaren 16a)<\/strong><\/li>\n<\/ul>\n<p><img decoding=\"async\" src=\"https:\/\/www.ideiakbizirik.com\/wp-content\/uploads\/2021\/09\/INPLANTALARIAK_3-LOGOAK-300x62.png\" alt=\"\" width=\"300\" height=\"62\" \/><\/p>\n<p>\u00a0 [:]\n","protected":false},"excerpt":{"rendered":"<p>Elektronika, Informazio eta Komunikazio Teknologiei buruzko aholkularitza teknologikoko saioak (EIKT)<\/p>\n","protected":false},"author":1,"featured_media":39972,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_robots_follow":"","_seopress_robots_imageindex":"","_seopress_robots_snippet":"","_seopress_robots_primary_cat":"","_seopress_robots_breadcrumbs":"","_seopress_robots_freeze_modified_date":"","_seopress_robots_custom_modified_date":"","_seopress_robots_canonical":"","_seopress_social_fb_title":"","_seopress_social_fb_desc":"","_seopress_social_fb_img":"","_seopress_social_fb_img_attachment_id":0,"_seopress_social_fb_img_width":0,"_seopress_social_fb_img_height":0,"_seopress_social_twitter_title":"","_seopress_social_twitter_desc":"","_seopress_social_twitter_img":"","_seopress_social_twitter_img_attachment_id":0,"_seopress_social_twitter_img_width":0,"_seopress_social_twitter_img_height":0,"_seopress_redirections_value":"","_seopress_redirections_enabled":"","_seopress_redirections_enabled_regex":"","_seopress_redirections_logged_status":"","_seopress_redirections_param":"","_seopress_redirections_type":0,"_seopress_analysis_target_kw":"","footnotes":""},"categories":[4346,4355,4363,4350],"tags":[4469,4514,4709],"class_list":["post-37850","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ekintzaile-komunitatea","category-ekintzailetza","category-formakuntza","category-ikastaroak","tag-ikt","tag-inplantalariak-eu","tag-spri-eu"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.ideiakbizirik.com\/eu\/wp-json\/wp\/v2\/posts\/37850","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ideiakbizirik.com\/eu\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ideiakbizirik.com\/eu\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ideiakbizirik.com\/eu\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ideiakbizirik.com\/eu\/wp-json\/wp\/v2\/comments?post=37850"}],"version-history":[{"count":0,"href":"https:\/\/www.ideiakbizirik.com\/eu\/wp-json\/wp\/v2\/posts\/37850\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ideiakbizirik.com\/eu\/wp-json\/wp\/v2\/media\/39972"}],"wp:attachment":[{"href":"https:\/\/www.ideiakbizirik.com\/eu\/wp-json\/wp\/v2\/media?parent=37850"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ideiakbizirik.com\/eu\/wp-json\/wp\/v2\/categories?post=37850"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ideiakbizirik.com\/eu\/wp-json\/wp\/v2\/tags?post=37850"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}